{"id":1185,"date":"2019-07-10T20:17:58","date_gmt":"2019-07-10T18:17:58","guid":{"rendered":"http:\/\/www.kananas.com\/ecoledemusiquedupaysdecharlieubelmont\/wp-content\/uploads\/sites\/877\/2019\/05\/64960930_381514289143017_2526508361478832128_n.jpg"},"modified":"2019-07-10T20:17:58","modified_gmt":"2019-07-10T18:17:58","slug":"64960930_381514289143017_2526508361478832128_n","status":"inherit","type":"attachment","link":"https:\/\/www.kananas.com\/ecoledemusiquedupaysdecharlieubelmont\/2018\/04\/02\/la-fete-de-la-musique\/64960930_381514289143017_2526508361478832128_n\/","title":{"rendered":"64960930_381514289143017_2526508361478832128_n"},"author":906,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_crdt_document":""},"class_list":["post-1185","attachment","type-attachment","status-inherit","hentry"],"filename":"64960930_381514289143017_2526508361478832128_n.jpg","filesize":68041,"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.kananas.com\/ecoledemusiquedupaysdecharlieubelmont\/wp-content\/uploads\/sites\/877\/2019\/05\/64960930_381514289143017_2526508361478832128_n.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/www.kananas.com\/ecoledemusiquedupaysdecharlieubelmont\/wp-content\/uploads\/sites\/877\/2019\/05\/64960930_381514289143017_2526508361478832128_n-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.kananas.com\/ecoledemusiquedupaysdecharlieubelmont\/wp-content\/uploads\/sites\/877\/2019\/05\/64960930_381514289143017_2526508361478832128_n-300x225.jpg 300w, https:\/\/www.kananas.com\/ecoledemusiquedupaysdecharlieubelmont\/wp-content\/uploads\/sites\/877\/2019\/05\/64960930_381514289143017_2526508361478832128_n-768x576.jpg 768w, https:\/\/www.kananas.com\/ecoledemusiquedupaysdecharlieubelmont\/wp-content\/uploads\/sites\/877\/2019\/05\/64960930_381514289143017_2526508361478832128_n-370x278.jpg 370w, https:\/\/www.kananas.com\/ecoledemusiquedupaysdecharlieubelmont\/wp-content\/uploads\/sites\/877\/2019\/05\/64960930_381514289143017_2526508361478832128_n.jpg 960w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":960,"height":720,"file":"2019\/05\/64960930_381514289143017_2526508361478832128_n.jpg","sizes":{"thumbnail":{"file":"64960930_381514289143017_2526508361478832128_n-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/www.kananas.com\/ecoledemusiquedupaysdecharlieubelmont\/wp-content\/uploads\/sites\/877\/2019\/05\/64960930_381514289143017_2526508361478832128_n-150x150.jpg"},"medium":{"file":"64960930_381514289143017_2526508361478832128_n-300x225.jpg","width":300,"height":225,"mime_type":"image\/jpeg","source_url":"https:\/\/www.kananas.com\/ecoledemusiquedupaysdecharlieubelmont\/wp-content\/uploads\/sites\/877\/2019\/05\/64960930_381514289143017_2526508361478832128_n-300x225.jpg"},"medium_large":{"file":"64960930_381514289143017_2526508361478832128_n-768x576.jpg","width":768,"height":576,"mime_type":"image\/jpeg","source_url":"https:\/\/www.kananas.com\/ecoledemusiquedupaysdecharlieubelmont\/wp-content\/uploads\/sites\/877\/2019\/05\/64960930_381514289143017_2526508361478832128_n-768x576.jpg"},"oblique-entry-thumb":{"file":"64960930_381514289143017_2526508361478832128_n-370x278.jpg","width":370,"height":278,"mime_type":"image\/jpeg","source_url":"https:\/\/www.kananas.com\/ecoledemusiquedupaysdecharlieubelmont\/wp-content\/uploads\/sites\/877\/2019\/05\/64960930_381514289143017_2526508361478832128_n-370x278.jpg"},"full":{"file":"64960930_381514289143017_2526508361478832128_n.jpg","width":960,"height":720,"mime_type":"image\/jpeg","source_url":"https:\/\/www.kananas.com\/ecoledemusiquedupaysdecharlieubelmont\/wp-content\/uploads\/sites\/877\/2019\/05\/64960930_381514289143017_2526508361478832128_n.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":1074,"source_url":"https:\/\/www.kananas.com\/ecoledemusiquedupaysdecharlieubelmont\/wp-content\/uploads\/sites\/877\/2019\/05\/64960930_381514289143017_2526508361478832128_n.jpg","_links":{"self":[{"href":"https:\/\/www.kananas.com\/ecoledemusiquedupaysdecharlieubelmont\/wp-json\/wp\/v2\/media\/1185","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kananas.com\/ecoledemusiquedupaysdecharlieubelmont\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.kananas.com\/ecoledemusiquedupaysdecharlieubelmont\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.kananas.com\/ecoledemusiquedupaysdecharlieubelmont\/wp-json\/wp\/v2\/users\/906"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kananas.com\/ecoledemusiquedupaysdecharlieubelmont\/wp-json\/wp\/v2\/comments?post=1185"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":1074,"href":"https:\/\/www.kananas.com\/ecoledemusiquedupaysdecharlieubelmont\/wp-json\/wp\/v2\/posts\/1074"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}