{"id":5310,"date":"2020-12-21T14:15:36","date_gmt":"2020-12-21T13:15:36","guid":{"rendered":"http:\/\/www.kananas.com\/myassociation962\/?p=5310"},"modified":"2020-12-21T14:56:09","modified_gmt":"2020-12-21T13:56:09","slug":"des-medailles-de-concorde-pour-nos-jeunes-diplomes-2020","status":"publish","type":"post","link":"https:\/\/www.kananas.com\/myassociation962\/des-medailles-de-concorde-pour-nos-jeunes-diplomes-2020\/","title":{"rendered":"Des m\u00e9dailles de Concorde pour nos jeunes dipl\u00f4m\u00e9s 2020"},"content":{"rendered":"<p style=\"text-align: justify\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-5313 alignleft\" src=\"http:\/\/www.kananas.com\/myassociation962\/wp-content\/uploads\/sites\/280\/2020\/12\/Diplo\u0302me\u0301s-2020-Chevreul-4-scaled.jpg\" alt=\"\" width=\"308\" height=\"202\" srcset=\"https:\/\/www.kananas.com\/myassociation962\/wp-content\/uploads\/sites\/280\/2020\/12\/Diplo\u0302me\u0301s-2020-Chevreul-4-scaled.jpg 2560w, https:\/\/www.kananas.com\/myassociation962\/wp-content\/uploads\/sites\/280\/2020\/12\/Diplo\u0302me\u0301s-2020-Chevreul-4-300x196.jpg 300w, https:\/\/www.kananas.com\/myassociation962\/wp-content\/uploads\/sites\/280\/2020\/12\/Diplo\u0302me\u0301s-2020-Chevreul-4-1024x671.jpg 1024w, https:\/\/www.kananas.com\/myassociation962\/wp-content\/uploads\/sites\/280\/2020\/12\/Diplo\u0302me\u0301s-2020-Chevreul-4-768x503.jpg 768w, https:\/\/www.kananas.com\/myassociation962\/wp-content\/uploads\/sites\/280\/2020\/12\/Diplo\u0302me\u0301s-2020-Chevreul-4-1536x1006.jpg 1536w, https:\/\/www.kananas.com\/myassociation962\/wp-content\/uploads\/sites\/280\/2020\/12\/Diplo\u0302me\u0301s-2020-Chevreul-4-2048x1341.jpg 2048w\" sizes=\"auto, (max-width: 308px) 100vw, 308px\" \/>Depuis sept ans, nous avions pris l\u2019habitude de r\u00e9unir \u00e0 la rentr\u00e9e scolaire tous les jeunes ayant pass\u00e9 avec succ\u00e8s l\u2019examen de fin d\u2019ann\u00e9e leur donnant droit \u00e0 un dipl\u00f4me sanctionnant leur scolarit\u00e9. Cette ann\u00e9e, Covid oblige, cette sympathique manifestation n\u2019a pas pu se d\u00e9rouler dans les conditions habituelles, mais chacun a re\u00e7u sa m\u00e9daille, une cr\u00e9ation originale et personnalis\u00e9e, r\u00e9alis\u00e9e par La Monnaie de Paris, \u00e0 l\u2019occasion des No\u00ebl organis\u00e9s dans les maisons fin d\u00e9cembre.<\/p>\n<p style=\"text-align: justify\">Le pr\u00e9sident de Concorde, Claude Chirouse et des membres du conseil <img loading=\"lazy\" decoding=\"async\" class=\"wp-image-5316 alignright\" src=\"http:\/\/www.kananas.com\/myassociation962\/wp-content\/uploads\/sites\/280\/2020\/12\/Capture-de\u0301cran-2020-12-21-a\u0300-14.46.01.png\" alt=\"\" width=\"229\" height=\"326\" srcset=\"https:\/\/www.kananas.com\/myassociation962\/wp-content\/uploads\/sites\/280\/2020\/12\/Capture-de\u0301cran-2020-12-21-a\u0300-14.46.01.png 656w, https:\/\/www.kananas.com\/myassociation962\/wp-content\/uploads\/sites\/280\/2020\/12\/Capture-de\u0301cran-2020-12-21-a\u0300-14.46.01-211x300.png 211w\" sizes=\"auto, (max-width: 229px) 100vw, 229px\" \/>d\u2019administration \u00e9taient pr\u00e9sents, aux c\u00f4t\u00e9s des personnels, pour saluer ces jeunes et leur remettre ce joli cadeau qui r\u00e9compense les efforts fournis.<\/p>\n<p>40 jeunes, accompagn\u00e9s par leur \u00e9ducateur r\u00e9f\u00e9rent, ont \u00e9t\u00e9 mis \u00e0 l\u2019honneur pour avoir obtenu les dipl\u00f4mes suivants\u00a0:<\/p>\n<ul>\n<li>\u00a0\u00a07 bacs\u00a0: 1 bac STMG, 1 bac S, 1 bac ES, 3 bacs pro (2 Gestion administrative), 1 accompagnement soins et services \u00e0 la personne), 1 bac STI2D,<\/li>\n<li>14 brevets des coll\u00e8ges (dont 1 mention AB, 1 mention B et 1 mention TB),<\/li>\n<li>15 CAP (1 boulangerie, 1 carrelage, 1 carrelage mosa\u00efque, 2 carrosserie, 2 cuisine, 3 \u00e9lectricit\u00e9, 1 fleuriste, 1 m\u00e9canique auto, 1 menuiserie, 1 p\u00e2tisserie, 1 peinture),<\/li>\n<li>\u00a0\u00a02 BEP\u00a0: 1 vente, 1 accompagnement soins et services \u00e0 la personne<\/li>\n<li>\u00a0\u00a02 CFG<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-5315 alignleft\" src=\"http:\/\/www.kananas.com\/myassociation962\/wp-content\/uploads\/sites\/280\/2020\/12\/Diplo\u0302me\u0301s-2020-Gagny-1-13.jpg\" alt=\"\" width=\"288\" height=\"216\" srcset=\"https:\/\/www.kananas.com\/myassociation962\/wp-content\/uploads\/sites\/280\/2020\/12\/Diplo\u0302me\u0301s-2020-Gagny-1-13.jpg 640w, https:\/\/www.kananas.com\/myassociation962\/wp-content\/uploads\/sites\/280\/2020\/12\/Diplo\u0302me\u0301s-2020-Gagny-1-13-300x225.jpg 300w\" sizes=\"auto, (max-width: 288px) 100vw, 288px\" \/>Ces c\u00e9r\u00e9monies, jumel\u00e9es avec les arbres de No\u00ebl dans chaque maison, ont \u00e9t\u00e9 un vrai moment de convivialit\u00e9 avant un peu de repos pour mieux poursuivre une ann\u00e9e scolaire chamboul\u00e9e par les contraintes sanitaires. Elles ont \u00e9t\u00e9 l\u2019occasion de rappeler que le taux de r\u00e9ussites aux examens des jeunes des maisons Concorde s\u2019inscrit parfaitement dans les moyennes nationales quand elles ne sont pas sup\u00e9rieures.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Un grand MERCI aux \u00e9ducateurs, \u00e0 tous les personnels de l\u2019association pour leur engagement et f\u00e9licitations aux jeunes dont le travail a \u00e9t\u00e9 r\u00e9compens\u00e9.<\/p>\n<p style=\"text-align: right\">Pierre Girault, vice-pr\u00e9sident de Concorde<\/p>\n<p>&nbsp;<\/p>\n<div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Depuis sept ans, nous avions pris l\u2019habitude de r\u00e9unir \u00e0 la rentr\u00e9e scolaire tous les jeunes ayant pass\u00e9 avec succ\u00e8s<\/p>\n","protected":false},"author":288,"featured_media":5320,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","_crdt_document":"","footnotes":""},"categories":[167,5],"tags":[61],"class_list":["post-5310","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-la-lettre-n75","category-vie-de-lassociation","tag-pierre-girault"],"_links":{"self":[{"href":"https:\/\/www.kananas.com\/myassociation962\/wp-json\/wp\/v2\/posts\/5310","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kananas.com\/myassociation962\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.kananas.com\/myassociation962\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.kananas.com\/myassociation962\/wp-json\/wp\/v2\/users\/288"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kananas.com\/myassociation962\/wp-json\/wp\/v2\/comments?post=5310"}],"version-history":[{"count":7,"href":"https:\/\/www.kananas.com\/myassociation962\/wp-json\/wp\/v2\/posts\/5310\/revisions"}],"predecessor-version":[{"id":5322,"href":"https:\/\/www.kananas.com\/myassociation962\/wp-json\/wp\/v2\/posts\/5310\/revisions\/5322"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.kananas.com\/myassociation962\/wp-json\/wp\/v2\/media\/5320"}],"wp:attachment":[{"href":"https:\/\/www.kananas.com\/myassociation962\/wp-json\/wp\/v2\/media?parent=5310"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.kananas.com\/myassociation962\/wp-json\/wp\/v2\/categories?post=5310"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.kananas.com\/myassociation962\/wp-json\/wp\/v2\/tags?post=5310"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}