{"id":5847,"date":"2022-02-23T16:37:40","date_gmt":"2022-02-23T15:37:40","guid":{"rendered":"http:\/\/www.kananas.com\/myassociation962\/?p=5847"},"modified":"2022-02-28T16:34:30","modified_gmt":"2022-02-28T15:34:30","slug":"vacances-de-noel-a-coubron-pour-la-maison-marie-foilaine-desolneux","status":"publish","type":"post","link":"https:\/\/www.kananas.com\/myassociation962\/vacances-de-noel-a-coubron-pour-la-maison-marie-foilaine-desolneux\/","title":{"rendered":"Vacances de No\u00ebl \u00e0 Coubron pour la maison Marie Foilaine Desolneux"},"content":{"rendered":"<p style=\"text-align: justify\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-5849 alignleft\" src=\"http:\/\/www.kananas.com\/myassociation962\/wp-content\/uploads\/sites\/280\/2022\/02\/Noe\u0308l-2021-a\u0300-Coubron-1-300x199.jpg\" alt=\"\" width=\"528\" height=\"350\" srcset=\"https:\/\/www.kananas.com\/myassociation962\/wp-content\/uploads\/sites\/280\/2022\/02\/Noe\u0308l-2021-a\u0300-Coubron-1-300x199.jpg 300w, https:\/\/www.kananas.com\/myassociation962\/wp-content\/uploads\/sites\/280\/2022\/02\/Noe\u0308l-2021-a\u0300-Coubron-1.jpg 716w\" sizes=\"auto, (max-width: 528px) 100vw, 528px\" \/>La f\u00eate de No\u00ebl du 14 d\u00e9cembre s\u2019est d\u00e9roul\u00e9e de fa\u00e7on festive, malgr\u00e9 les contraintes sanitaires et le protocole.<\/p>\n<p style=\"text-align: justify\">Un grand merci au p\u00e8re No\u00ebl et \u00e0 ses lutins pour leur distribution de cadeaux enflamm\u00e9s.<\/p>\n<p style=\"text-align: justify\">Nous tenons \u00e0 remercier le Lions Club qui est venu sur la structure le 23 d\u00e9cembre 2021 pour apporter des cadeaux \u00e0 nos plus jeunes. Ceux-ci ont pu choisir diff\u00e9rents jeux adapt\u00e9s \u00e0 leur \u00e2ge. Depuis maintenant deux ans, le Lions Club offre des jouets pour les plus jeunes.<\/p>\n<p style=\"text-align: justify\">Le 24 d\u00e9cembre, le groupe s\u2019est rendu au grand Rex voir la f\u00e9\u00e9rie des eaux, visionner le film Tous en sc\u00e8ne 2. Ils ont \u00e9galement pu visiter le cin\u00e9ma.<\/p>\n<p style=\"text-align: justify\">Le 25 d\u00e9cembre, ils ont assist\u00e9 \u00e0 une repr\u00e9sentation du Cirque Ph\u00e9nix. Petits et grands ont eu des \u00e9toiles plein les yeux tant la repr\u00e9sentation \u00e9tait grandiose.<\/p>\n<p style=\"text-align: justify\">Au programme \u00e9galement visite de Paris avec les plus jeunes, les vitrines de No\u00ebl des grands magasins et les illuminations de la Tour Eiffel.<\/p>\n<p style=\"text-align: justify\">Le 31 d\u00e9cembre, le groupe s\u2019est rendu au restaurant pour f\u00eater le nouvel an et, d\u00e8s le retour, jeux et blind test avec une \u00e9quipe au top.<img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-5851 aligncenter\" src=\"http:\/\/www.kananas.com\/myassociation962\/wp-content\/uploads\/sites\/280\/2022\/02\/Capture-de\u0301cran-2022-02-23-a\u0300-16.38.46-231x300.png\" alt=\"\" width=\"231\" height=\"300\" srcset=\"https:\/\/www.kananas.com\/myassociation962\/wp-content\/uploads\/sites\/280\/2022\/02\/Capture-de\u0301cran-2022-02-23-a\u0300-16.38.46-231x300.png 231w, https:\/\/www.kananas.com\/myassociation962\/wp-content\/uploads\/sites\/280\/2022\/02\/Capture-de\u0301cran-2022-02-23-a\u0300-16.38.46.png 332w\" sizes=\"auto, (max-width: 231px) 100vw, 231px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La f\u00eate de No\u00ebl du 14 d\u00e9cembre s\u2019est d\u00e9roul\u00e9e de fa\u00e7on festive, malgr\u00e9 les contraintes sanitaires et le protocole. Un<\/p>\n","protected":false},"author":288,"featured_media":5848,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","_crdt_document":"","footnotes":""},"categories":[198,4],"tags":[],"class_list":["post-5847","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-la-lettre-n77","category-vie-des-maisons"],"_links":{"self":[{"href":"https:\/\/www.kananas.com\/myassociation962\/wp-json\/wp\/v2\/posts\/5847","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kananas.com\/myassociation962\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.kananas.com\/myassociation962\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.kananas.com\/myassociation962\/wp-json\/wp\/v2\/users\/288"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kananas.com\/myassociation962\/wp-json\/wp\/v2\/comments?post=5847"}],"version-history":[{"count":4,"href":"https:\/\/www.kananas.com\/myassociation962\/wp-json\/wp\/v2\/posts\/5847\/revisions"}],"predecessor-version":[{"id":5867,"href":"https:\/\/www.kananas.com\/myassociation962\/wp-json\/wp\/v2\/posts\/5847\/revisions\/5867"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.kananas.com\/myassociation962\/wp-json\/wp\/v2\/media\/5848"}],"wp:attachment":[{"href":"https:\/\/www.kananas.com\/myassociation962\/wp-json\/wp\/v2\/media?parent=5847"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.kananas.com\/myassociation962\/wp-json\/wp\/v2\/categories?post=5847"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.kananas.com\/myassociation962\/wp-json\/wp\/v2\/tags?post=5847"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}