{"id":3495,"date":"2024-07-08T16:28:14","date_gmt":"2024-07-08T14:28:14","guid":{"rendered":"https:\/\/www.kananas.com\/uplegess\/?p=3495"},"modified":"2024-07-08T18:02:47","modified_gmt":"2024-07-08T16:02:47","slug":"retour-sur-la-reunion-des-responsables-de-departement-le-mercredi-29-mai-a-psb","status":"publish","type":"post","link":"https:\/\/www.kananas.com\/uplegess\/2024\/07\/08\/retour-sur-la-reunion-des-responsables-de-departement-le-mercredi-29-mai-a-psb\/","title":{"rendered":"Retour sur la r\u00e9union des responsables de d\u00e9partement Langues et cultures le mercredi 29 mai \u00e0 PSB"},"content":{"rendered":"<blockquote><p>Th\u00e9matique de la table ronde &#8211; <strong>Comment imaginer le d\u00e9partement Langues et Cultures de demain : Quelles priorit\u00e9s, quels objectifs et quelles m\u00e9thodes de travail pour les cinq prochaines ann\u00e9es ?<\/strong><\/p><\/blockquote>\n<p><span style=\"font-size: 12pt\">Une r\u00e9union des responsables de d\u00e9partement a marqu\u00e9 comme chaque ann\u00e9e, l&rsquo;ouverture du congr\u00e8s de l&rsquo;UPLEGESS. Elle s&rsquo;est tenue \u00e0 Paris School of Business (PSB) et a \u00e9t\u00e9 co-anim\u00e9e par Nora Sanchez de PSB et Sophie Sousa de IMT-BS\/TSP. \u00a0<\/span><\/p>\n<p><span style=\"font-size: 12pt\">J\u00f6rg Eschenauer, pr\u00e9sident de l&rsquo;UPLEGESS, a tout d&rsquo;abord soulign\u00e9 l&rsquo;importance de pr\u00e9parer un nouveau questionnaire pour une enqu\u00eate en 2025, (10 ans apr\u00e8s celle de 2015) <strong>\u00ab L&rsquo;enseignement des langues dans les Grandes \u00c9coles : \u00e9tat des lieux et pr\u00e9conisations \u00bb, <\/strong>l\u2019occasion de recueillir des donn\u00e9es essentielles aupr\u00e8s des d\u00e9partements de langues et cultures de nos \u00e9coles-membres.<\/span><\/p>\n<p><!--more--><\/p>\n<p><span style=\"font-size: 12pt\">Les discussions se sont articul\u00e9es ensuite autour de la th\u00e9matique centrale.<strong>\u00a0<\/strong><\/span><span style=\"font-size: 12pt\">Nous avons examin\u00e9 les d\u00e9fis majeurs de l&rsquo;enseignement des langues et cultures, les priorit\u00e9s pour les d\u00e9partements, et comment l&rsquo;UPLEGESS pouvait contribuer \u00e0 am\u00e9liorer le dialogue entre enseignants, directions et institutions. <\/span><span style=\"font-size: 12pt\">Nous avons \u00e9galement explor\u00e9 les strat\u00e9gies \u00e0 adopter face \u00e0 des \u00e9tudiants qui apprennent diff\u00e9remment \u00e0 l&rsquo;\u00e8re de l&rsquo;IA, de l&rsquo;acc\u00e8s illimit\u00e9 au savoir et de l&rsquo;apprentissage informel.<\/span><\/p>\n<p><span style=\"font-size: 12pt\">Ces \u00e9changes ont \u00e9t\u00e9 extr\u00eamement enrichissants et promettent de stimuler des initiatives innovantes pour l&rsquo;enseignement des langues et cultures dans nos institutions. <\/span><span style=\"font-size: 12pt\">Un grand merci \u00e0 Steve Brown, Jean-Marc D\u00e9pierre, H\u00e9l\u00e8ne Duranton, Carole Gally, Jennifer Lucas, et Linda Koiran, pour leurs riches contributions \u00e9clairantes.<\/span><\/p>\n<p><em>Contribution r\u00e9dactionnelle de Nora Sanchez<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Th\u00e9matique de la table ronde &#8211; Comment imaginer le d\u00e9partement Langues et Cultures de demain : Quelles priorit\u00e9s, quels objectifs et quelles m\u00e9thodes de travail pour les cinq prochaines ann\u00e9es ? Une r\u00e9union des responsables de d\u00e9partement a marqu\u00e9 comme chaque ann\u00e9e, l&rsquo;ouverture du congr\u00e8s de l&rsquo;UPLEGESS. Elle s&rsquo;est tenue \u00e0 Paris School of Business (PSB) et a \u00e9t\u00e9 co-anim\u00e9e<\/p>\n","protected":false},"author":1147,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_crdt_document":"","footnotes":""},"categories":[9,6],"tags":[],"class_list":["post-3495","post","type-post","status-publish","format-standard","hentry","category-actu-congres","category-actualites-de-luplegess"],"_links":{"self":[{"href":"https:\/\/www.kananas.com\/uplegess\/wp-json\/wp\/v2\/posts\/3495","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kananas.com\/uplegess\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.kananas.com\/uplegess\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.kananas.com\/uplegess\/wp-json\/wp\/v2\/users\/1147"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kananas.com\/uplegess\/wp-json\/wp\/v2\/comments?post=3495"}],"version-history":[{"count":6,"href":"https:\/\/www.kananas.com\/uplegess\/wp-json\/wp\/v2\/posts\/3495\/revisions"}],"predecessor-version":[{"id":3510,"href":"https:\/\/www.kananas.com\/uplegess\/wp-json\/wp\/v2\/posts\/3495\/revisions\/3510"}],"wp:attachment":[{"href":"https:\/\/www.kananas.com\/uplegess\/wp-json\/wp\/v2\/media?parent=3495"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.kananas.com\/uplegess\/wp-json\/wp\/v2\/categories?post=3495"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.kananas.com\/uplegess\/wp-json\/wp\/v2\/tags?post=3495"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}