{"id":2615,"date":"2023-01-13T09:38:20","date_gmt":"2023-01-13T08:38:20","guid":{"rendered":"https:\/\/www.kananas.com\/vudenhaut-france\/?p=2615"},"modified":"2025-01-01T10:45:59","modified_gmt":"2025-01-01T09:45:59","slug":"theorique-ppl-en-poche","status":"publish","type":"post","link":"https:\/\/www.kananas.com\/vudenhaut-france\/2023\/01\/13\/theorique-ppl-en-poche\/","title":{"rendered":"Th\u00e9orique PPL en poche !"},"content":{"rendered":"<p style=\"text-align: center\">Toutes nos f\u00e9licitations \u00e0 <strong>ANTOINE<\/strong> qui vient d&rsquo;obtenir ce mercredi 11 janvier 2023 l&rsquo;ensemble des \u00e9preuves du <strong>Th\u00e9orique PPL !<\/strong><\/p>\n<p style=\"text-align: center\">Nous lui souhaitons maintenant de belles navigations \u00e0 venir !<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Toutes nos f\u00e9licitations \u00e0 ANTOINE qui vient d&rsquo;obtenir ce mercredi 11 janvier 2023 l&rsquo;ensemble des \u00e9preuves du Th\u00e9orique PPL ! Nous lui souhaitons maintenant de belles navigations \u00e0 venir !<\/p>\n","protected":false},"author":1102,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_crdt_document":"","footnotes":""},"categories":[6],"tags":[],"class_list":["post-2615","post","type-post","status-publish","format-standard","hentry","category-les-anciens-articles"],"_links":{"self":[{"href":"https:\/\/www.kananas.com\/vudenhaut-france\/wp-json\/wp\/v2\/posts\/2615","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kananas.com\/vudenhaut-france\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.kananas.com\/vudenhaut-france\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.kananas.com\/vudenhaut-france\/wp-json\/wp\/v2\/users\/1102"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kananas.com\/vudenhaut-france\/wp-json\/wp\/v2\/comments?post=2615"}],"version-history":[{"count":1,"href":"https:\/\/www.kananas.com\/vudenhaut-france\/wp-json\/wp\/v2\/posts\/2615\/revisions"}],"predecessor-version":[{"id":2616,"href":"https:\/\/www.kananas.com\/vudenhaut-france\/wp-json\/wp\/v2\/posts\/2615\/revisions\/2616"}],"wp:attachment":[{"href":"https:\/\/www.kananas.com\/vudenhaut-france\/wp-json\/wp\/v2\/media?parent=2615"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.kananas.com\/vudenhaut-france\/wp-json\/wp\/v2\/categories?post=2615"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.kananas.com\/vudenhaut-france\/wp-json\/wp\/v2\/tags?post=2615"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}